{"id":10,"date":"2023-01-24T08:09:48","date_gmt":"2023-01-24T08:09:48","guid":{"rendered":"https:\/\/demosites.royal-elementor-addons.com\/car-repair-v1\/?page_id=10"},"modified":"2025-12-18T11:28:26","modified_gmt":"2025-12-18T11:28:26","slug":"services","status":"publish","type":"page","link":"https:\/\/www.energtech.com.ph\/index.php\/services\/","title":{"rendered":"Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10\" class=\"elementor elementor-10\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e949d28 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e949d28\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7f6cf0\" data-id=\"a7f6cf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad17c9c elementor-widget elementor-widget-heading\" data-id=\"ad17c9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21bba8fc elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no elementor-invisible\" data-id=\"21bba8fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;,&quot;shape_divider_top&quot;:&quot;opacity-fan&quot;,&quot;animation&quot;:&quot;slideInDown&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 283.5 19.6\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.33\" d=\"M0 0L0 18.8 141.8 4.1 283.5 18.8 283.5 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.33\" d=\"M0 0L0 12.6 141.8 4 283.5 12.6 283.5 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.33\" d=\"M0 0L0 6.4 141.8 4 283.5 6.4 283.5 0z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L0 1.2 141.8 4 283.5 1.2 283.5 0z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5317e818\" data-id=\"5317e818\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-233a1977 elementor-widget elementor-widget-heading\" data-id=\"233a1977\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Services <br> We Offer \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e2d47e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2e2d47e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2aebf9f1 elementor-invisible\" data-id=\"2aebf9f1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c70ee68 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"5c70ee68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Preventive Maintenance<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2cfcf434 elementor-invisible\" data-id=\"2cfcf434\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68f3c9ea wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"68f3c9ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span> Supply &amp; Installation of Gensets<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1a714f1 elementor-invisible\" data-id=\"1a714f1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34e7f26a wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"34e7f26a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-19.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Fuel Filtration<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3d4c5466 elementor-invisible\" data-id=\"3d4c5466\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-344a8fa8 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"344a8fa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Diesel Engine Overhauling<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6302e0af elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6302e0af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-369e3a61 elementor-invisible\" data-id=\"369e3a61\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-323c7bc3 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"323c7bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span> Fabrication of Genset Auxiliary Equip<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-466bfbb1 elementor-invisible\" data-id=\"466bfbb1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e0febc0 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"3e0febc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Electro-Mechanical Retrofitting<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-779780b7 elementor-invisible\" data-id=\"779780b7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c02faae wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"1c02faae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-19.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Fuel Filtration and Conditioning Works<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-225345b8 elementor-invisible\" data-id=\"225345b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-651cce1f wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"651cce1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Fabrication &amp; Install of Exhaust Mufflers<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-38c04519 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"38c04519\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6f77d008 elementor-invisible\" data-id=\"6f77d008\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b36b55b wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"7b36b55b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Periodic Preventive Maintenance of Diesel Engines<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-24a03b8a elementor-invisible\" data-id=\"24a03b8a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a277a03 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"5a277a03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Maintenance &amp; Reconditioning of Main Alternators<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4d07535b elementor-invisible\" data-id=\"4d07535b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d0ade31 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"2d0ade31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-19.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span> Install, Test and Commissioning of Genset<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-39a8016a elementor-invisible\" data-id=\"39a8016a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15e67329 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"15e67329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Maintenance of Transformers &amp; Electrical Switchgear<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7c21c7ef elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7c21c7ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-24fb3414 elementor-invisible\" data-id=\"24fb3414\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23e2c66a wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"23e2c66a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Thermal Scanning of Electrical Equipment<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5ca67423 elementor-invisible\" data-id=\"5ca67423\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a7b40a4 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"4a7b40a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Equipment Audit &amp; Technical Analysis<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2b27f96d elementor-invisible\" data-id=\"2b27f96d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1050702e wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"1050702e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-19.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Retrofitting &amp; Synchronizing Panel<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-66b93bf4 elementor-invisible\" data-id=\"66b93bf4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22af9ac7 wpr-promo-box-style-cover elementor-widget elementor-widget-wpr-promo-box\" data-id=\"22af9ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-promo-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"wpr-promo-box wpr-animation-wrap\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wpr-promo-box-image\">\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-image wpr-bg-anim-zoom-in wpr-anim-timing-ease-default\" style=\"background-image:url(https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-15.png);\"><\/div>\n\t\t\t\t\t<div class=\"wpr-promo-box-bg-overlay wpr-border-anim-oscar\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-promo-box-content\">\n\n\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2023\/01\/pic-18.png\" >\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h3 class=\"wpr-promo-box-title\"><span>Main Alternator Maintenance<\/span><\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-promo-box-btn-wrap\">\n\t\t\t\t\t\t<a class=\"wpr-promo-box-btn\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-promo-box-btn-text\">Read More<\/span>\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b654ef elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no elementor-invisible\" data-id=\"4b654ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-add621e\" data-id=\"add621e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08ea57d elementor-widget elementor-widget-heading\" data-id=\"08ea57d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schedule Your Appointment Today<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9790f06 elementor-widget elementor-widget-text-editor\" data-id=\"9790f06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"block-title\"><div class=\"block-title__description\"><p class=\"info\">Your Automotive Repair &amp; Maintenance Service Specialist<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0ca10 wpr-button-icon-style-inline wpr-button-icon-position-right elementor-widget elementor-widget-wpr-button\" data-id=\"1f0ca10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-button.default\">\n\t\t\t\t\t\t\n\t\t\t\n\t\t\n\t\t<div class=\"wpr-button-wrap elementor-clearfix\">\n\t\t<a class=\"wpr-button wpr-button-effect wpr-button-none\" data-text=\"\" href=\"#link\">\n\t\t\t\n\t\t\t<span class=\"wpr-button-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"wpr-button-text\">Schedule Appointment<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3118a6b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3118a6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-791d669\" data-id=\"791d669\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73f0f93 elementor-widget elementor-widget-heading\" data-id=\"73f0f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ENER-G-TECH <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc57fe elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fbc57fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-288920a wpr-advanced-accordion-icon-side-box elementor-widget elementor-widget-wpr-advanced-accordion\" data-id=\"288920a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;active_item&quot;:1}\" data-widget_type=\"wpr-advanced-accordion.default\">\n\t\t\t\t\t\n            <div class=\"wpr-advanced-accordion\" data-accordion-type=\"accordion\" data-active-index=\"1\" data-accordion-trigger=\"click\" data-interaction-speed=\"0.4\">\n\n\t\t\t\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-desktop\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">ABOUT US<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>About ENER-G-TECH:<br class=\"html-br\" \/>A trusted name in machinery and equipment repair, ENER-G-TECH specializes in the supply, installation, and preventive maintenance of diesel engine-generator sets and related electrical and mechanical systems.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-cog\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M610.5 373.3c2.6-14.1 2.6-28.5 0-42.6l25.8-14.9c3-1.7 4.3-5.2 3.3-8.5-6.7-21.6-18.2-41.2-33.2-57.4-2.3-2.5-6-3.1-9-1.4l-25.8 14.9c-10.9-9.3-23.4-16.5-36.9-21.3v-29.8c0-3.4-2.4-6.4-5.7-7.1-22.3-5-45-4.8-66.2 0-3.3.7-5.7 3.7-5.7 7.1v29.8c-13.5 4.8-26 12-36.9 21.3l-25.8-14.9c-2.9-1.7-6.7-1.1-9 1.4-15 16.2-26.5 35.8-33.2 57.4-1 3.3.4 6.8 3.3 8.5l25.8 14.9c-2.6 14.1-2.6 28.5 0 42.6l-25.8 14.9c-3 1.7-4.3 5.2-3.3 8.5 6.7 21.6 18.2 41.1 33.2 57.4 2.3 2.5 6 3.1 9 1.4l25.8-14.9c10.9 9.3 23.4 16.5 36.9 21.3v29.8c0 3.4 2.4 6.4 5.7 7.1 22.3 5 45 4.8 66.2 0 3.3-.7 5.7-3.7 5.7-7.1v-29.8c13.5-4.8 26-12 36.9-21.3l25.8 14.9c2.9 1.7 6.7 1.1 9-1.4 15-16.2 26.5-35.8 33.2-57.4 1-3.3-.4-6.8-3.3-8.5l-25.8-14.9zM496 400.5c-26.8 0-48.5-21.8-48.5-48.5s21.8-48.5 48.5-48.5 48.5 21.8 48.5 48.5-21.7 48.5-48.5 48.5zM224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm201.2 226.5c-2.3-1.2-4.6-2.6-6.8-3.9l-7.9 4.6c-6 3.4-12.8 5.3-19.6 5.3-10.9 0-21.4-4.6-28.9-12.6-18.3-19.8-32.3-43.9-40.2-69.6-5.5-17.7 1.9-36.4 17.9-45.7l7.9-4.6c-.1-2.6-.1-5.2 0-7.8l-7.9-4.6c-16-9.2-23.4-28-17.9-45.7.9-2.9 2.2-5.8 3.2-8.7-3.8-.3-7.5-1.2-11.4-1.2h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c10.1 0 19.5-3.2 27.2-8.5-1.2-3.8-2-7.7-2-11.8v-9.2z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">\u201cSTOP POLLUTING, START SAVING,\u201d<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>Driven by its advocacy \u201cSTOP POLLUTING, START SAVING,\u201d the company champions innovative, eco-friendly technologies \u2014 including its Mobile Fuel Filtration System and SUPERTECH, a green device from Italy that reduces exhaust gas emissions by up to 80% and fuel consumption by 12%.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-telegram-plane\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">ENER-G-TECH continues to prove<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>ENER-G-TECH continues to prove that business growth and environmental sustainability can go hand in hand.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d82afa elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"0d82afa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d94000 elementor-widget elementor-widget-image\" data-id=\"0d94000\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"796\" height=\"1024\" src=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_j676lzj676lzj676-796x1024.png\" class=\"attachment-large size-large wp-image-914\" alt=\"\" srcset=\"https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_j676lzj676lzj676-796x1024.png 796w, https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_j676lzj676lzj676-233x300.png 233w, https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_j676lzj676lzj676-768x987.png 768w, https:\/\/www.energtech.com.ph\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_j676lzj676lzj676.png 896w\" sizes=\"(max-width: 796px) 100vw, 796px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Services Our Services We Offer Preventive Maintenance Read More Supply &amp; Installation of Gensets Read More Fuel Filtration Read More Diesel Engine Overhauling Read More Fabrication of Genset Auxiliary Equip Read More Electro-Mechanical Retrofitting Read More Fuel Filtration and Conditioning Works Read More Fabrication &amp; Install of Exhaust Mufflers Read More Periodic Preventive Maintenance of Diesel Engines Read More Maintenance &amp; Reconditioning of Main Alternators Read More Install, Test and Commissioning of Genset Read More Maintenance of Transformers &amp; Electrical Switchgear Read More Thermal Scanning of Electrical Equipment Read More Equipment Audit &amp; Technical Analysis Read More Retrofitting &amp; Synchronizing Panel Read More Main Alternator Maintenance Read More Schedule Your Appointment Today Your Automotive Repair &amp; Maintenance Service Specialist Schedule Appointment ENER-G-TECH ABOUT US About ENER-G-TECH:A trusted name in machinery and equipment repair, ENER-G-TECH specializes in the supply, installation, and preventive maintenance of diesel engine-generator sets and related electrical and mechanical systems. \u201cSTOP POLLUTING, START SAVING,\u201d Driven by its advocacy \u201cSTOP POLLUTING, START SAVING,\u201d the company champions innovative, eco-friendly technologies \u2014 including its Mobile Fuel Filtration System and SUPERTECH, a green device from Italy that reduces exhaust gas emissions by up to 80% and fuel consumption by 12%. ENER-G-TECH continues to prove ENER-G-TECH continues to prove that business growth and environmental sustainability can go hand in hand.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":12,"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":937,"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions\/937"}],"wp:attachment":[{"href":"https:\/\/www.energtech.com.ph\/index.php\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}